{"id":65419,"date":"2025-05-09T14:18:34","date_gmt":"2025-05-09T17:18:34","guid":{"rendered":"https:\/\/vocesdelacomuna15.com.ar\/press\/?p=65419"},"modified":"2025-05-09T14:21:02","modified_gmt":"2025-05-09T17:21:02","slug":"la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/","title":{"rendered":"La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado"},"content":{"rendered":"\n<p>Reconocimiento a las organizaciones que promueven la diversidad generacional y desarrollan pol\u00edticas, productos y servicios orientados al segmento +50.<\/p>\n\n\n\n<p>En el auditorio de la Sede del Gobierno de la Ciudad de Buenos Aires, se realiz\u00f3 la presentaci\u00f3n de los fundamentos y beneficios del programa de Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado, as\u00ed como las bases y condiciones para acceder a la certificaci\u00f3n. El mismo tiene como misi\u00f3n validar, acompa\u00f1ar y visibilizar a aquellas organizaciones que implementan pol\u00edticas amigables con todas las edades, fomentando entornos laborales inclusivos, el dise\u00f1o de productos para personas mayores y la promoci\u00f3n del talento intergeneracional.<\/p>\n\n\n\n<p>En el encuentro, el ministro de Desarrollo Humano y H\u00e1bitat de la Ciudad, Gabriel Mraida, destac\u00f3: \u201dEl Sello Plateado es mucho m\u00e1s que un reconocimiento a las empresas que apuestan por la econom\u00eda plateada, es el compromiso de hacer una Ciudad m\u00e1s inclusiva donde las personas mayores sean protagonistas; donde cada persona pueda desarrollar su prop\u00f3sito, tenga la edad que tenga\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0113-1024x683.avif\" alt=\"\" class=\"wp-image-65421\" srcset=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0113-1024x683.avif 1024w, https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0113-300x200.avif 300w, https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0113-768x512.avif 768w, https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0113-1536x1024.avif 1536w, https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0113-2048x1365.avif 2048w, https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0113-1080x720.avif 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\">Un evento con protagonismo intergeneracional<\/h1>\n\n\n\n<p>La presentaci\u00f3n cont\u00f3 con la exposici\u00f3n de un panel de expertos que abordaron desde distintos \u00e1ngulos la importancia de la diversidad generacional en las empresas y del fomento de la econom\u00eda plateada. Participaron: Luis Guastini, Presidente y CEO ManpowerGroup Argentina; Laura Briano, Directora RRHH LATAM Accenture; Adri\u00e1n Barreto, Coordinador de Alianzas en Diagonal Asociaci\u00f3n Civil; Fabiana Gadow, CEO Korn Ferry Argentina; Alberto Chab, profesional independiente, psicoanalista; M\u00f3nica Alejandra Rodr\u00edguez, PM empleada Bar Las Nonas y Andrea Falcone, Fundadora de Silver Economy Forum.<\/p>\n\n\n\n<p>Tambi\u00e9n particip\u00f3 del encuentro, Mercedes Joury, subsecretaria de Personas Mayores que dijo: \u201cCreemos firmemente que <strong>la edad no es un l\u00edmite<\/strong>, sino una fortaleza. Las personas mayores de 50 a\u00f1os tienen una trayectoria valiosa, habilidades desarrolladas a lo largo del tiempo y una mirada que enriquece cualquier entorno de trabajo\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Modalidades de certificaci\u00f3n:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cultura<\/strong><strong>InterGen:<\/strong>para organizaciones que integran la diversidad etaria en sus pr\u00e1cticas laborales.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Innovador<\/strong><strong>Silver:<\/strong>para quienes desarrollan soluciones orientadas a mejorar la calidad de vida de personas mayores.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Metodolog\u00eda de certificaci\u00f3n<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La certificaci\u00f3n consta de cinco etapas: elecci\u00f3n del tipo de certificaci\u00f3n, clasificaci\u00f3n de la organizaci\u00f3n, evaluaci\u00f3n mediante formulario, revisi\u00f3n de evidencias y emisi\u00f3n del informe final con certificaci\u00f3n y recomendaciones de mejora.<\/li>\n<\/ul>\n\n\n\n<h1 class=\"wp-block-heading\">Un compromiso con el futuro<\/h1>\n\n\n\n<p>La Ciudad reconoce que el envejecimiento poblacional es una realidad demogr\u00e1fica en crecimiento, y busca acompa\u00f1ar este proceso desde una perspectiva positiva, inclusiva y estrat\u00e9gica. La Certificaci\u00f3n Impacto Silver representa una oportunidad para que el sector privado se sume activamente a este cambio cultural, econ\u00f3mico y social.<\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_65419\" class=\"pvc_stats all  \" data-element-id=\"65419\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Reconocimiento a las organizaciones que promueven la diversidad generacional y desarrollan pol\u00edticas, productos y servicios orientados al segmento +50. En el auditorio de la Sede del Gobierno de la Ciudad de Buenos Aires, se realiz\u00f3 la presentaci\u00f3n de los fundamentos y beneficios del programa de Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado, as\u00ed como las bases [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_65419\" class=\"pvc_stats all  \" data-element-id=\"65419\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":65420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[],"class_list":["post-65419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":47,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-09T17:18:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T17:21:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0099-scaled.avif\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado\",\"datePublished\":\"2025-05-09T17:18:34+00:00\",\"dateModified\":\"2025-05-09T17:21:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/\"},\"wordCount\":469,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/DSC_0099-scaled.avif\",\"articleSection\":[\"Ciudad\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/\",\"name\":\"La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/DSC_0099-scaled.avif\",\"datePublished\":\"2025-05-09T17:18:34+00:00\",\"dateModified\":\"2025-05-09T17:21:02+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/DSC_0099-scaled.avif\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/DSC_0099-scaled.avif\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1778629429\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1778629429\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1778629429\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/","og_locale":"es_ES","og_type":"article","og_title":"La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2025-05-09T17:18:34+00:00","article_modified_time":"2025-05-09T17:21:02+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0099-scaled.avif","type":"image\/jpeg"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado","datePublished":"2025-05-09T17:18:34+00:00","dateModified":"2025-05-09T17:21:02+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/"},"wordCount":469,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0099-scaled.avif","articleSection":["Ciudad"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/","name":"La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0099-scaled.avif","datePublished":"2025-05-09T17:18:34+00:00","dateModified":"2025-05-09T17:21:02+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0099-scaled.avif","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2025\/05\/DSC_0099-scaled.avif","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-ciudad-acompana-el-lanzamiento-de-la-certificacion-impactosilver-sello-plateado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"La Ciudad acompa\u00f1a el lanzamiento de la Certificaci\u00f3n Impacto Silver \u2013 Sello Plateado"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1778629429","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1778629429","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1778629429","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/65419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=65419"}],"version-history":[{"count":2,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/65419\/revisions"}],"predecessor-version":[{"id":65424,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/65419\/revisions\/65424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/65420"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=65419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=65419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=65419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}