{"id":62464,"date":"2024-01-01T08:41:00","date_gmt":"2024-01-01T11:41:00","guid":{"rendered":"https:\/\/vocesdelacomuna15.com.ar\/?p=62464"},"modified":"2023-12-29T20:43:40","modified_gmt":"2023-12-29T23:43:40","slug":"los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/","title":{"rendered":"Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La ceremonia de apertura se realiz\u00f3 en el Movistar Arena y estuvo el presidente Milei. Fuente: P\u00e1gina 12 (Publicada el 29 de diciembre de 2023)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Link a nota original: <a href=\"https:\/\/www.pagina12.com.ar\/699549-los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-\">https:\/\/www.pagina12.com.ar\/699549-los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Juegos <strong>Macabeos Panamericanos<\/strong> comenzaron hoy (por el viernes 29 de diciembre) en Buenos Aires, y finalizar\u00e1n el 4 de enero pr\u00f3ximo.&nbsp; La ceremonia de apertura se realiz\u00f3 en el estadio Movistar Arena en el barrio porte\u00f1o de Villa Crespo, donde desfilaron todas las delegaciones con la presencia de distintas personalidades de relevancia del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la Naci\u00f3n, Javier Milei, se present\u00f3 en la celebraci\u00f3n y luego dio un discurso de bienvenida al resto de los pa\u00edses. Se presentaron tambi\u00e9n&nbsp;<strong>Karina Milei<\/strong> (secretaria de la Presidencia), <strong>Patricia Bullrich<\/strong> (Ministra de Seguridad de la Naci\u00f3n), <strong>Jorge Macri<\/strong> (Jefe de Gobierno de la Ciudad de Buenos Aires), <strong>Marc Stanley<\/strong> (embajador de Estados Unidos), <strong>Mario Moccia<\/strong> (titular del Comit\u00e9 Ol\u00edmpico Argentino), <strong>Mariano C\u00faneo Libarona<\/strong> (Ministro de Justicia de la Naci\u00f3n), y&nbsp;<strong>Luis Petri<\/strong> (Ministro de Defensa de la Naci\u00f3n).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de las competiciones deportivas que se llevar\u00e1n a cabo en el <strong>Club N\u00e1utico Hacoaj <\/strong>(sede Tigre), en la <strong>Sociedad Hebraica Argentina<\/strong> (sede Pilar) y en el Cissab (ubicado en la localidad de Trist\u00e1n Su\u00e1rez), habr\u00e1 recorridos tur\u00edsticos, Kabalat Shabat comunitarios y actividades sociales y culturales para todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un contexto dif\u00edcil y de resiliencia del pueblo jud\u00edo, los Juegos, <strong>organizados por FACCMA (Federaci\u00f3n Argentina de Centros Comunitarios Macabeos) <\/strong>brindan la oportunidad de volver a ser sede del evento comunitario con m\u00e1s participantes de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento deportivo, social y cultural convoca a delegaciones de todo el continente y algunos pa\u00edses europeos a competir en diversas disciplinas deportivas. <strong>La participaci\u00f3n es de aproximadamente 4.000 atletas de diversos pa\u00edses, <\/strong>que estar\u00e1n divididos entre las ya mencionadas sedes de competici\u00f3n donde se practicar\u00e1n los siguientes deportes: B\u00e1squet, Futsal, F\u00fatbol, Gimnasia Art\u00edstica, Gimnasia R\u00edtmica, Golf, Handball, Hockey, Macabi Man\/woman, Macabi Run (Triatl\u00f3n, running, aguas abiertas), Ciclismo, Nataci\u00f3n, Netball, P\u00e1del, Pickleball, Softball, <strong>Tenis, Tenis de mesa, V\u00f3ley, V\u00f3ley playa.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de un evento de inter\u00e9s nacional abierto a la comunidad que busca promover el desarrollo integral de la comunidad jud\u00eda, a trav\u00e9s de la difusi\u00f3n de los valores macabeos y la construcci\u00f3n de un legado institucional, deportivo y cultural.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos Juegos macabeos <strong>buscan la excelencia en todas sus \u00e1reas<\/strong> para que sea un evento inolvidable tanto para la delegaci\u00f3n Argentina, como para todas las delegaciones del resto del mundo. Internamente trabajamos para dejar un legado a nuestra Federaci\u00f3n como as\u00ed tambi\u00e9n a la regi\u00f3n y a nivel internacional\u201d, sostuvo <strong>Lucas Makarz, Director de Comunicaciones de los juegos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Juegos Panamericanos se realizan cada cuatro a\u00f1os alternando dos a\u00f1os y dos a\u00f1os con las <strong>Macabeadas Mundiales.<\/strong> En el pa\u00eds, se llevaron a cabo anteriormente en 1995 y en 2007.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Acerca de FACCMA:<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Federaci\u00f3n Argentina de Centros Comunitarios Macabeos es una organizaci\u00f3n sin fines de lucro que nuclea a 43 instituciones, tales como centros comunitarios, entidades socio deportivas y clubes. Todas ellas conforman <strong>una extensa red nacional comunitaria<\/strong> que agrupa, en la Federaci\u00f3n, a 50.000 personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caracteres: 3.149<\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_62464\" class=\"pvc_stats all  \" data-element-id=\"62464\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>La ceremonia de apertura se realiz\u00f3 en el Movistar Arena y estuvo el presidente Milei. Fuente: P\u00e1gina 12 (Publicada el 29 de diciembre de 2023) Link a nota original: https:\/\/www.pagina12.com.ar\/699549-los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos- Los Juegos Macabeos Panamericanos comenzaron hoy (por el viernes 29 de diciembre) en Buenos Aires, y finalizar\u00e1n el 4 de enero pr\u00f3ximo.&nbsp; La ceremonia de [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_62464\" class=\"pvc_stats all  \" data-element-id=\"62464\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":62466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[27,32],"tags":[],"class_list":["post-62464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-vcre","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":44,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-01T11:41:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/01\/macabeos.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires\",\"datePublished\":\"2024-01-01T11:41:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/\"},\"wordCount\":578,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/macabeos.jpeg\",\"articleSection\":[\"Deportes\",\"Villa Crespo\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/\",\"name\":\"Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/macabeos.jpeg\",\"datePublished\":\"2024-01-01T11:41:00+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/macabeos.jpeg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/macabeos.jpeg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/","og_locale":"es_ES","og_type":"article","og_title":"Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2024-01-01T11:41:00+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/01\/macabeos.jpeg","type":"image\/jpeg"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires","datePublished":"2024-01-01T11:41:00+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/"},"wordCount":578,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/01\/macabeos.jpeg","articleSection":["Deportes","Villa Crespo"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/","name":"Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/01\/macabeos.jpeg","datePublished":"2024-01-01T11:41:00+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/01\/macabeos.jpeg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/01\/macabeos.jpeg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/los-xv-juegos-macabeos-panamericanos-se-iniciaron-en-buenos-aires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"Los XV Juegos Macabeos Panamericanos se iniciaron en Buenos Aires"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/62464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=62464"}],"version-history":[{"count":1,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/62464\/revisions"}],"predecessor-version":[{"id":62465,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/62464\/revisions\/62465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/62466"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=62464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=62464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=62464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}