{"id":54553,"date":"2021-09-06T02:02:20","date_gmt":"2021-09-06T05:02:20","guid":{"rendered":"http:\/\/vocesdelacomuna15.com.ar\/wordpress\/?p=54553"},"modified":"2021-09-01T14:09:50","modified_gmt":"2021-09-01T17:09:50","slug":"vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/","title":{"rendered":"Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La ministra de Salud dijo que a partir de noviembre evaluar\u00e1n brindar un refuerzo a personas de riesgo. Fuente: Noticias Urbanas (Publicada el 31 de agosto)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Link a nota original: <a href=\"https:\/\/www.noticiasurbanas.com.ar\/noticias\/vizzotti-anticipo-cuando-se-aplicaran-la-tercera-dosis-en-la-argentina\/\">https:\/\/www.noticiasurbanas.com.ar\/noticias\/vizzotti-anticipo-cuando-se-aplicaran-la-tercera-dosis-en-la-argentina\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Ministra de Salud de la Naci\u00f3n&nbsp;<strong>Carla Vizzotti asegur\u00f3 que desde noviembre se\nanalizar\u00e1 la posibilidad de aplicar un tercer componente de vacuna contra el\ncoronavirus a personas con factores de riesgo para disminuir el impacto de\neventuales contagios de variante Delta.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo hizo en el marco de una nueva reuni\u00f3n del Consejo\nFederal de Salud (Cofesa) de la que participaron los 24 ministros y ministras\nde salud de los distritos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La titular de la cartera sanitaria nacional traz\u00f3 los\nobjetivos que se plantea el gobierno de cara a fin de a\u00f1o. Habl\u00f3 de&nbsp;<strong>\u201ccontinuar en septiembre con las segundas dosis,\nen octubre con adolescentes y a partir de noviembre evaluar si estamos en\ncondiciones de hacer un refuerzo en personas que tienen determinadas\ncondiciones de salud e inmunodeprimidas\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de una estrategia que ya se tiene en cuenta en\nmuchos pa\u00edses del mundo en los que el avance de la variante Delta es mayor\nimportante debido al nivel de contagiosidad que presenta, lo que hace necesaria\nla aplicaci\u00f3n de un nuevo componente para el esquema de vacunaci\u00f3n de las\npersonas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con las declaraciones que hizo la ministra durante la\nconferencia de prensa que dio en Terrazas de Portezuelo, la casa de gobierno\npuntana, dej\u00f3 en claro que Argentina evaluar\u00e1 la necesidad de que se aplique\nuna nueva dosis ante la variante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En principio, adelant\u00f3 que ejecutar\u00edan la estrategia en\npersonas con determinadas condiciones de riesgo en su salud, como\ninmunodepresi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vizzotti tambi\u00e9n\ndestac\u00f3 el \u201cavance sostenido\u201d de la campa\u00f1a de inmunizaci\u00f3n contra el\ncoronavirus. Dijo que del total de la poblaci\u00f3n vacunada en Argentina, la\nmayor\u00eda tiene dos dosis y que se super\u00f3 el objetivo de agosto, con un 70,3% de\npersonas de 50 a\u00f1os y m\u00e1s con esquema completo.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La funcionaria expres\u00f3 adem\u00e1s: \u201cHay muchas ganas de vacunarse en el pa\u00eds, algo que habla de mucho compromiso de la poblaci\u00f3n y conciencia respecto del impacto colectivo que eso genera, por eso es algo que nosotros ponemos en valor\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foto: Noticias Urbanas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caracteres: 1.975<\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_54553\" class=\"pvc_stats all  \" data-element-id=\"54553\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>La ministra de Salud dijo que a partir de noviembre evaluar\u00e1n brindar un refuerzo a personas de riesgo. Fuente: Noticias Urbanas (Publicada el 31 de agosto) Link a nota original: https:\/\/www.noticiasurbanas.com.ar\/noticias\/vizzotti-anticipo-cuando-se-aplicaran-la-tercera-dosis-en-la-argentina\/ La Ministra de Salud de la Naci\u00f3n&nbsp;Carla Vizzotti asegur\u00f3 que desde noviembre se analizar\u00e1 la posibilidad de aplicar un tercer componente de vacuna contra [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_54553\" class=\"pvc_stats all  \" data-element-id=\"54553\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":54554,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-54553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":441,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-06T05:02:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/09\/31-08-21_apertura_cofesa-750x500.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina\",\"datePublished\":\"2021-09-06T05:02:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/\"},\"wordCount\":402,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/31-08-21_apertura_cofesa-750x500.jpeg\",\"articleSection\":[\"Sociedad\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/\",\"name\":\"Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/31-08-21_apertura_cofesa-750x500.jpeg\",\"datePublished\":\"2021-09-06T05:02:20+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/31-08-21_apertura_cofesa-750x500.jpeg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/31-08-21_apertura_cofesa-750x500.jpeg\",\"width\":750,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/","og_locale":"es_ES","og_type":"article","og_title":"Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2021-09-06T05:02:20+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/09\/31-08-21_apertura_cofesa-750x500.jpeg","type":"image\/jpeg"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina","datePublished":"2021-09-06T05:02:20+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/"},"wordCount":402,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/09\/31-08-21_apertura_cofesa-750x500.jpeg","articleSection":["Sociedad"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/","name":"Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/09\/31-08-21_apertura_cofesa-750x500.jpeg","datePublished":"2021-09-06T05:02:20+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/09\/31-08-21_apertura_cofesa-750x500.jpeg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/09\/31-08-21_apertura_cofesa-750x500.jpeg","width":750,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/vizzotti-anticipo-cuando-aplicaran-la-tercera-dosis-en-la-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"Vizzotti anticip\u00f3 cu\u00e1ndo aplicar\u00e1n la tercera dosis en la Argentina"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/54553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=54553"}],"version-history":[{"count":3,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/54553\/revisions"}],"predecessor-version":[{"id":54557,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/54553\/revisions\/54557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/54554"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=54553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=54553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=54553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}