{"id":54468,"date":"2021-08-13T23:58:15","date_gmt":"2021-08-14T02:58:15","guid":{"rendered":"http:\/\/vocesdelacomuna15.com.ar\/wordpress\/?p=54468"},"modified":"2021-08-13T23:58:23","modified_gmt":"2021-08-14T02:58:23","slug":"teatro-crossmedia-alimanas-ponzonosas","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/","title":{"rendered":"Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermandades beligerantes, soledades pobladas, cambios de g\u00e9nero, amores diferentes, misterios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva dramaturgia, escrita y dirigida por Alberto Mad\u00edn se estrenar\u00e1 el domingo 5 de septiembre a las 17 horas en el Centro Cultural Paraje Artes\u00f3n, ubicado en la calle Estado de Palestina 919, en el barrio porte\u00f1o de Almagro. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un ambiente cerrado, claustrof\u00f3bico\naparecen dos seres Hermelinda y \u00darsula, enmara\u00f1ados en una discusi\u00f3n dom\u00e9stica.\nHermelinda se nos presenta como una mujer col\u00e9rica, dominante, envuelta en\nfantas\u00edas del pasado. \u00darsula, m\u00e1s terrenal aparece calmando, con dulzura y\npaciencia a Herme. Poco a poco se nos va revelando su historia familiar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay toques y tonos humor\u00edsticos en algunas\nsituaciones y reiteraciones simb\u00f3licas con el tema de dar cuerda a los relojes\n(detenci\u00f3n del tiempo en el pasado).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre ambas hay un supuesto juego de ama y\nesclava: una siempre en la irrealidad (Herme) y la otra (\u00darsula) en la realidad\ndel aqu\u00ed y ahora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un tercer personaje irrumpe desde el\nexterior y rompe el tedio de la rutina de estas mujeres, un extra\u00f1o que trae\nuna visi\u00f3n diferente, aunque est\u00e1 enajenado en su propia b\u00fasqueda por su amada\nperdida. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inmersos en este atractivo juego teatral\nnos dejamos llevar a un mundo de fantas\u00eda\/realidad simb\u00f3lica. Realismo m\u00e1gico\nen todo su colorido esplendor, complejidad y sofisticaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alberto Mad\u00edn crea un mundo m\u00e1gico cerrado,\nen el que todo puede suceder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Paraje Artes\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Direcci\u00f3n: Estado de Palestina 919, C1182\nC1182ADI, Buenos Aires, Argentina<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono: +54 11 3288-1008<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Instagram:  @alimanasponzonosas <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Facebook: www.facebook.com\/teatrocrossmedia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Whastapp: 115980-0454<\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_54468\" class=\"pvc_stats all  \" data-element-id=\"54468\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Hermandades beligerantes, soledades pobladas, cambios de g\u00e9nero, amores diferentes, misterios. La nueva dramaturgia, escrita y dirigida por Alberto Mad\u00edn se estrenar\u00e1 el domingo 5 de septiembre a las 17 horas en el Centro Cultural Paraje Artes\u00f3n, ubicado en la calle Estado de Palestina 919, en el barrio porte\u00f1o de Almagro. En un ambiente cerrado, claustrof\u00f3bico [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_54468\" class=\"pvc_stats all  \" data-element-id=\"54468\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":54470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-54468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":272,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-14T02:58:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-14T02:58:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/08\/alima\u00f1asred.png\" \/>\n\t<meta property=\"og:image:width\" content=\"517\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas\",\"datePublished\":\"2021-08-14T02:58:15+00:00\",\"dateModified\":\"2021-08-14T02:58:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/\"},\"wordCount\":280,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/alima\u00f1asred.png\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/\",\"name\":\"Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/alima\u00f1asred.png\",\"datePublished\":\"2021-08-14T02:58:15+00:00\",\"dateModified\":\"2021-08-14T02:58:23+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/alima\u00f1asred.png\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/alima\u00f1asred.png\",\"width\":517,\"height\":513},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/teatro-crossmedia-alimanas-ponzonosas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/","og_locale":"es_ES","og_type":"article","og_title":"Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2021-08-14T02:58:15+00:00","article_modified_time":"2021-08-14T02:58:23+00:00","og_image":[{"width":517,"height":513,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/08\/alima\u00f1asred.png","type":"image\/png"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas","datePublished":"2021-08-14T02:58:15+00:00","dateModified":"2021-08-14T02:58:23+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/"},"wordCount":280,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/08\/alima\u00f1asred.png","articleSection":["Cultura"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/","name":"Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/08\/alima\u00f1asred.png","datePublished":"2021-08-14T02:58:15+00:00","dateModified":"2021-08-14T02:58:23+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/08\/alima\u00f1asred.png","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2021\/08\/alima\u00f1asred.png","width":517,"height":513},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/teatro-crossmedia-alimanas-ponzonosas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"Teatro Crossmedia: Alima\u00f1as Ponzo\u00f1osas"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1788307505","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/54468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=54468"}],"version-history":[{"count":1,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/54468\/revisions"}],"predecessor-version":[{"id":54471,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/54468\/revisions\/54471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/54470"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=54468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=54468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=54468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}