{"id":52778,"date":"2020-09-24T16:57:58","date_gmt":"2020-09-24T19:57:58","guid":{"rendered":"http:\/\/vocesdelacomuna15.com.ar\/wordpress\/?p=52778"},"modified":"2020-09-24T16:58:03","modified_gmt":"2020-09-24T19:58:03","slug":"la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/","title":{"rendered":"La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gracias a una investigaci\u00f3n, \u00a0detuvo a un m\u00fasico que comercializaba estupefacientes en su domicilio y a bordo de un taxi por los barrios de Saavedra, N\u00fa\u00f1ez y Villa Urquiza. Fuente: Ministerio de Justicia y Seguridad CABA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Personal del Departamento Contravenciones y Faltas,\nperteneciente a la Divisi\u00f3n Investigaciones Delictivas de la<strong> Polic\u00eda de la Ciudad<\/strong>, llev\u00f3 a cabo en los\n\u00faltimos d\u00edas un allanamiento en un domicilio de la avenida Donato \u00c1lvarez al\n2.200 por orden del Juzgado Penal Contravencional y de Faltas N\u00famero 13, a\ncargo de la doctora Moral por comercializaci\u00f3n de drogas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los efectivos policiales llevaron a cabo una\ninvestigaci\u00f3n para dar con el paradero de un hombre que vend\u00eda estupefacientes\ny los repart\u00eda a bordo de un taxi con un arreglo de citas previas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez determinado el domicilio del sospechoso, se\nobserv\u00f3 que tambi\u00e9n comercializaba las sustancias desde su casa y por tal\nmotivo se organiz\u00f3 el operativo del que participaron veedores del Cuerpo de\nInvestigaci\u00f3n Judicial y personal del grupo especial DOEM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que un comprador sali\u00f3 del domicilio, los\npolic\u00edas ingresaron al mismo y lo detuvieron. En el lugar, los oficiales\nincautaron una balanza de precisi\u00f3n, bolsas con coca\u00edna, un bloque de ladrillo\nde coca\u00edna y una caja con dinero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al consultar con magistrado a cargo del caso, se dispuso\nel secuestro del material y la detenci\u00f3n del imputado y su traslado a la\nalcaid\u00eda de la Polic\u00eda de la Ciudad de la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente y Foto: Ministerio de Justicia y Seguridad\nCABA<\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_52778\" class=\"pvc_stats all  \" data-element-id=\"52778\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Gracias a una investigaci\u00f3n, \u00a0detuvo a un m\u00fasico que comercializaba estupefacientes en su domicilio y a bordo de un taxi por los barrios de Saavedra, N\u00fa\u00f1ez y Villa Urquiza. Fuente: Ministerio de Justicia y Seguridad CABA Personal del Departamento Contravenciones y Faltas, perteneciente a la Divisi\u00f3n Investigaciones Delictivas de la Polic\u00eda de la Ciudad, llev\u00f3 [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_52778\" class=\"pvc_stats all  \" data-element-id=\"52778\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":52779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[29,28],"tags":[],"class_list":["post-52778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lapa","category-policial","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":302,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-24T19:57:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-24T19:58:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/dealer2409.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal\",\"datePublished\":\"2020-09-24T19:57:58+00:00\",\"dateModified\":\"2020-09-24T19:58:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/\"},\"wordCount\":283,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/dealer2409.jpg\",\"articleSection\":[\"La Paternal\",\"Policial\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/\",\"name\":\"La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/dealer2409.jpg\",\"datePublished\":\"2020-09-24T19:57:58+00:00\",\"dateModified\":\"2020-09-24T19:58:03+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/dealer2409.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/dealer2409.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/","og_locale":"es_ES","og_type":"article","og_title":"La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2020-09-24T19:57:58+00:00","article_modified_time":"2020-09-24T19:58:03+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/dealer2409.jpg","type":"image\/jpeg"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal","datePublished":"2020-09-24T19:57:58+00:00","dateModified":"2020-09-24T19:58:03+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/"},"wordCount":283,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/dealer2409.jpg","articleSection":["La Paternal","Policial"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/","name":"La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/dealer2409.jpg","datePublished":"2020-09-24T19:57:58+00:00","dateModified":"2020-09-24T19:58:03+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/dealer2409.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/dealer2409.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/la-policia-de-la-ciudad-detuvo-al-musico-dealer-de-la-paternal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"La Polic\u00eda de la Ciudad detuvo al m\u00fasico dealer de La Paternal"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=52778"}],"version-history":[{"count":1,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52778\/revisions"}],"predecessor-version":[{"id":52780,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52778\/revisions\/52780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/52779"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=52778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=52778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=52778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}