{"id":52743,"date":"2020-09-15T15:49:20","date_gmt":"2020-09-15T18:49:20","guid":{"rendered":"http:\/\/vocesdelacomuna15.com.ar\/wordpress\/?p=52743"},"modified":"2021-06-16T19:15:43","modified_gmt":"2021-06-16T22:15:43","slug":"estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/","title":{"rendered":"Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gracias a un convenio firmado entre la Facultad y ACUMAR, se abri\u00f3 una convocatoria para estudiantes de todas las carreras, interesados en realizar su proyecto final relacionado a tem\u00e1ticas ambientales, productivas y\/o sociales vinculadas a la Cuenca. Tendr\u00e1n tiempo hasta el 30 septiembre para presentar su propuesta.&nbsp;As\u00ed podr\u00e1n contribuir al saneamiento del r\u00edo m\u00e1s contaminado del pa\u00eds. Fuente: Agro.uba.ar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Facultad de Agronom\u00eda de la UBA, a trav\u00e9s de las\nC\u00e1tedras de Econom\u00eda General y Qu\u00edmica Inorg\u00e1nica y Anal\u00edtica, firm\u00f3 un\nconvenio de Cooperaci\u00f3n Interinstitucional con la Autoridad de Cuenca Matanza\nRiachuelo (ACUMAR), para implementar trabajos de investigaci\u00f3n que contribuyan\nal saneamiento del r\u00edo m\u00e1s contaminado del pa\u00eds.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA trav\u00e9s del convenio, ACUMAR y la FAUBA buscan aunar esfuerzos y\nfortalecer el trabajo conjunto, para crear espacios de intercambio de saberes y\nvisiones, y promover el desarrollo y aplicaci\u00f3n de los conocimientos adquiridos\npor los alumnos de la FAUBA a trav\u00e9s de proyectos, estudios, investigaciones,\ntesis de grado y\/o posgrado, que colaboren con las pol\u00edticas relacionadas con\nla mejora en la calidad de vida de los habitantes, la recomposici\u00f3n del\nambiente en todos sus componentes (agua, aire y suelo) y la prevenci\u00f3n de da\u00f1os\nen la cuenca del Matanza-Riachuelo\u201d, explic\u00f3 el&nbsp;<strong>Ing. Agr. Daniel Tomasini<\/strong>,\nProfesor del \u00c1rea de Econom\u00eda de los Recursos Naturales y Ambiente, de la\nC\u00e1tedra de Econom\u00eda General.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera, los estudiantes interesados en investigar sobre tem\u00e1ticas\nambientales, productivas y\/o sociales vinculadas a la Cuenca Matanza Riachuelo\npodr\u00e1n presentar su proyecto hasta el 30 de septiembre. La Facultad facilitar\u00e1\nel acceso a informaci\u00f3n y apoyo t\u00e9cnico en el marco de su convenio con la\nAutoridad de Cuenca Matanza Riachuelo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta Facultad tiene entre sus objetivos la ense\u00f1anza de diversas\ndisciplinas que se encuentran en la \u00f3rbita del inter\u00e9s de ACUMAR, y en funci\u00f3n\nde las actividades precedentes entre ambas instituciones, se ha motivado\nespecial inter\u00e9s en los estudiantes para desarrollar actividades de\ninvestigaci\u00f3n y extensi\u00f3n en esa jurisdicci\u00f3n\u201d, expuso Tomasini.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En materia de investigaci\u00f3n, la C\u00e1tedra de Qu\u00edmica Inorg\u00e1nica y Anal\u00edtica\ndesarrolla actividades desde 1998 en la cuenca, y m\u00e1s recientemente se han\nformalizado los viajes de estudio que anualmente se realizan en el curso de\nEconom\u00eda y Pol\u00edtica Ambiental (LiCiA) de la C\u00e1tedra de Econom\u00eda General.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, los proyectos de investigaci\u00f3n deber\u00e1n considerar que los\ntemas y espacios para el trabajo com\u00fan se relacionen a: Calidad ambiental.\nFuentes de contaminaci\u00f3n. Estad\u00edsticas \/Modelos de producci\u00f3n y contaminaci\u00f3n\/\nFitorremediaci\u00f3n\/ Calidad del paisaje. Intervenci\u00f3n de riberas\/ \u00c1reas\nprotegidas y biodiversidad\/ Control de ex\u00f3ticas invasoras\/ Infraestructura y\nrecursos h\u00eddricos\/ Fortalecimiento institucional. Normativa\/ Empleo verde y\ndesarrollo sostenible\/ Econom\u00eda circular\/ Capacitaci\u00f3n social (cooperativistas)\ny organizaci\u00f3n barrial\/Ordenamiento territorial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo de trabajo de la FAUBA promueve la presentaci\u00f3n de proyectos de\ntesis en el marco del convenio y facilita la vinculaci\u00f3n de los alumnos con los\ndocentes. Una vez cerrada la convocatoria, la coordinaci\u00f3n del convenio se\nreunir\u00e1 regularmente para acordar la admisi\u00f3n de proyectos, entre todas las\npropuestas presentadas por los estudiantes y\/o docentes de la FAUBA. Desde\nACUMAR acompa\u00f1ar\u00e1n a trav\u00e9s de contactos de estudiantes con integrantes de\n\u00e1reas del organismo vinculadas con el tema de trabajo propuesto, para analizar,\nevaluar y mejorar la propuesta; asesoramiento para el acceso a la informaci\u00f3n\nreunida por el organismo en sus distintas \u00e1reas de gesti\u00f3n, que pudieran ser\nrelevantes a los fines de los proyectos propuestos; y seguimiento de la\nactividad de los estudiantes a cargo de los proyectos de investigaci\u00f3n por\nrepresentantes definidos por cada \u00e1rea del organismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPonemos en consideraci\u00f3n de la comunidad esta oportunidad y la tem\u00e1tica\nabarcada, invitamos a los docentes de todas las c\u00e1tedras con posibilidad de\ndirigir proyectos de tesis de grado y posgrado en todas las carreras de la Facultad\ny esperamos una importante participaci\u00f3n de los estudiantes\u201d, concluy\u00f3 el Ing.\nDaniel Tomasini.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para m\u00e1s informaci\u00f3n comunicarse a convacumar@agro.uba.ar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente y Foto: Agro.uba.ar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caracteres: 3.893<\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_52743\" class=\"pvc_stats all  \" data-element-id=\"52743\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Gracias a un convenio firmado entre la Facultad y ACUMAR, se abri\u00f3 una convocatoria para estudiantes de todas las carreras, interesados en realizar su proyecto final relacionado a tem\u00e1ticas ambientales, productivas y\/o sociales vinculadas a la Cuenca. Tendr\u00e1n tiempo hasta el 30 septiembre para presentar su propuesta.&nbsp;As\u00ed podr\u00e1n contribuir al saneamiento del r\u00edo m\u00e1s contaminado [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_52743\" class=\"pvc_stats all  \" data-element-id=\"52743\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":52745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6,8],"tags":[],"class_list":["post-52743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro","category-sociedad","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":298,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-15T18:49:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-16T22:15:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/agro15092020.png\" \/>\n\t<meta property=\"og:image:width\" content=\"733\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo\",\"datePublished\":\"2020-09-15T18:49:20+00:00\",\"dateModified\":\"2021-06-16T22:15:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/\"},\"wordCount\":751,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/agro15092020.png\",\"articleSection\":[\"Agronom\u00eda\",\"Sociedad\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/\",\"name\":\"Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/agro15092020.png\",\"datePublished\":\"2020-09-15T18:49:20+00:00\",\"dateModified\":\"2021-06-16T22:15:43+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/agro15092020.png\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/agro15092020.png\",\"width\":733,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/","og_locale":"es_ES","og_type":"article","og_title":"Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2020-09-15T18:49:20+00:00","article_modified_time":"2021-06-16T22:15:43+00:00","og_image":[{"width":733,"height":486,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/agro15092020.png","type":"image\/png"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo","datePublished":"2020-09-15T18:49:20+00:00","dateModified":"2021-06-16T22:15:43+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/"},"wordCount":751,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/agro15092020.png","articleSection":["Agronom\u00eda","Sociedad"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/","name":"Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/agro15092020.png","datePublished":"2020-09-15T18:49:20+00:00","dateModified":"2021-06-16T22:15:43+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/agro15092020.png","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/09\/agro15092020.png","width":733,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/estudiantes-de-fauba-podran-realizar-la-tesis-en-la-cuenca-matanza-riachuelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"Estudiantes de FAUBA podr\u00e1n realizar la Tesis en la Cuenca Matanza-Riachuelo"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=52743"}],"version-history":[{"count":2,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52743\/revisions"}],"predecessor-version":[{"id":54155,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52743\/revisions\/54155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/52745"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=52743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=52743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=52743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}