{"id":52281,"date":"2020-06-01T11:34:26","date_gmt":"2020-06-01T14:34:26","guid":{"rendered":"http:\/\/vocesdelacomuna15.com.ar\/wordpress\/?p=52281"},"modified":"2020-06-01T14:23:21","modified_gmt":"2020-06-01T17:23:21","slug":"las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/","title":{"rendered":"Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El tr\u00e1mite fue iniciado por Norberto Zanzi, Presidente de la Biblioteca Popular Becci\u00fa, de La Paternal. La Defensor\u00eda del Pueblo present\u00f3 un Oficio para resolver la situaci\u00f3n. Plantean adaptarse al protocolo y entregar libros sin que los socios ingresen a las bibliotecas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Defensor\u00eda del Pueblo de la Ciudad Aut\u00f3noma de Buenos\nAires present\u00f3 un Oficio a la Direcci\u00f3n General de Promoci\u00f3n del Libro,\nBibliotecas y la Cultura del Ministerio de Cultura porte\u00f1o, tras el tr\u00e1mite\niniciado por Norberto Zanzi, Presidente de la Biblioteca Popular Becci\u00fa,\nubicada en el pasaje Nicol\u00e1s Granada 1660, barrio de La Paternal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los representantes de las bibliotecas populares porte\u00f1as,\nque son 35 en la Ciudad no saben si pueden abrir o no. Consultadas las\nautoridades, no tienen respuesta y como no hay resoluci\u00f3n al respecto, se\naconseja no abrir. Plantean una apertura parcial, adapt\u00e1ndose al protocolo por\nCOVID-19, que aparte de los cuidados generales, no permitir\u00eda el ingreso de los\nsocios a las bibliotecas sino que solo retiren libros en horarios pactados. \u201cLa\nimportancia de la lectura de un libro se acrecienta en estos momentos\u201d, expres\u00f3\nZanzi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reproducimos aqu\u00ed el Oficio que se present\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Defensor\u00eda del Pueblo- Ciudad Aut\u00f3noma de Buenos Aires <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C.A.B.A , 21 de mayo de 2020<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1ora Directora General<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Direcci\u00f3n General Promoci\u00f3n del\nLibro, Bibliotecas y la Cultura<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ministerio de Cultura<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gobierno de la Ciudad Aut\u00f3noma de Buenos Aires<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sra. Carla del Valle ARTUNDUAGA GONZ\u00c1LEZ<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S. \/ D.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ref.: Tr\u00e1mite n\u00ba 11.296\/20<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De mi consideraci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tengo el agrado de dirigirme a Ud. con relaci\u00f3n al\nTr\u00e1mite de referencia, iniciado por el se\u00f1or Norberto Zanzi, en su car\u00e1cter de\npresidente de la Biblioteca Popular \u201cJuan Mar\u00eda Becciu\u201d (Inscripci\u00f3n CONABIP n\u00b0\n1375), sita en el pasaje Nicol\u00e1s Granada 1660 de esta Ciudad, quien solicita se\nhabilite la apertura y el funcionamiento de las Bibliotecas Populares de esta\nCiudad durante el actual per\u00edodo de Aislamiento Social, Preventivo y Obligatorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El se\u00f1or Zanzi manifest\u00f3 en su presentaci\u00f3n ante esta\nDefensor\u00eda del Pueblo lo siguiente: <em>\u201c\u2026Lo que buscamos es que los socios\npidan libros, la Bibliotecaria los prepare y lo pasen a buscar por la puerta\n(sin ingresar a la Biblioteca). Esta actividad no influye en la cuarentena\nporque 1) empleado es uno solo, 2) son solo 4 horas por d\u00eda, 3) las bibliotecas\npopulares son 35 en todo CABA, nada en comparaci\u00f3n con los miles de comercios habilitados,\n4) Los socios son pocos (en los comercios cientos), 5) se llevan 3 libros por\nlo que tardan un mes en regresar, o sea vendr\u00edan una vez por mes y no 8 o m\u00e1s\ncomo pasar\u00e1 en los distintos comercios&#8230;\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, inform\u00f3 que no hab\u00eda obtenido respuesta a un\ncorreo electr\u00f3nico remitido a la Direcci\u00f3n General a su cargo en el que se\u00f1al\u00f3\nque: <em>\u201c\u2026En el mail que envi\u00e9 a Enrique puse mi propuesta de iniciar la\nactividad en<\/em> <em>las Bibliotecas Populares empezando inmediatamente pero\nsolamente a prestar libros con un protocolo. M\u00e1s<\/em> <em>adelante se puede\nregular talleres y otros actividades. Hay que tener en cuenta que los socios\nson pocos, en<\/em> <em>comparaci\u00f3n con clientes de un negocio, como se llevan\ntres libros vuelven en promedio cada tres semanas.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Todo ello hace que la\ncirculaci\u00f3n de los socios en la calle sea casi nula.\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, solicito a Ud. tenga a bien informar a esta\nDefensor\u00eda del Pueblo la respuesta suministrada al se\u00f1or Norberto Zanzi, as\u00ed\ncomo tambi\u00e9n brindar la informaci\u00f3n que estime corresponda con relaci\u00f3n a la apertura\ny el funcionamiento de las Bibliotecas Populares de esta Ciudad durante el\nper\u00edodo de Aislamiento Social, Preventivo y Obligatorio vigente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad Aut\u00f3noma de Buenos Aires, 21 de Mayo de 2020.-<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presente deber\u00e1 ser contestado en el plazo de d\u00edas de\nser recibido, conforme lo <strong>diez (10) <\/strong>dispuesto por la Ley n\u00ba 3 de la\nC.A.B.A. en sus art\u00edculos 13 y 31.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin otro particular, saludo a Ud. atentamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">gfl\/GL\/COECCyT\/CEDS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Firmado\ndigitalmente por:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Livia Edith RITONDO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caracteres: 3.904<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foto: Biblioteca\nBecci\u00fa en el aniversario de La Paternal (a\u00f1o 2017)- Voces de la Comuna 15<\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_52281\" class=\"pvc_stats all  \" data-element-id=\"52281\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>El tr\u00e1mite fue iniciado por Norberto Zanzi, Presidente de la Biblioteca Popular Becci\u00fa, de La Paternal. La Defensor\u00eda del Pueblo present\u00f3 un Oficio para resolver la situaci\u00f3n. Plantean adaptarse al protocolo y entregar libros sin que los socios ingresen a las bibliotecas. La Defensor\u00eda del Pueblo de la Ciudad Aut\u00f3noma de Buenos Aires present\u00f3 un [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_52281\" class=\"pvc_stats all  \" data-element-id=\"52281\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":52282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[24,29],"tags":[],"class_list":["post-52281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-lapa","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":392,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-01T14:34:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-01T17:23:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/becciu2805.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5152\" \/>\n\t<meta property=\"og:image:height\" content=\"3864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial\",\"datePublished\":\"2020-06-01T14:34:26+00:00\",\"dateModified\":\"2020-06-01T17:23:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/\"},\"wordCount\":717,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/becciu2805.jpg\",\"articleSection\":[\"Cultura\",\"La Paternal\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/\",\"name\":\"Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/becciu2805.jpg\",\"datePublished\":\"2020-06-01T14:34:26+00:00\",\"dateModified\":\"2020-06-01T17:23:21+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/becciu2805.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/becciu2805.jpg\",\"width\":5152,\"height\":3864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/","og_locale":"es_ES","og_type":"article","og_title":"Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2020-06-01T14:34:26+00:00","article_modified_time":"2020-06-01T17:23:21+00:00","og_image":[{"width":5152,"height":3864,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/becciu2805.jpg","type":"image\/jpeg"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial","datePublished":"2020-06-01T14:34:26+00:00","dateModified":"2020-06-01T17:23:21+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/"},"wordCount":717,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/becciu2805.jpg","articleSection":["Cultura","La Paternal"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/","name":"Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/becciu2805.jpg","datePublished":"2020-06-01T14:34:26+00:00","dateModified":"2020-06-01T17:23:21+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/becciu2805.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/becciu2805.jpg","width":5152,"height":3864},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/las-bibliotecas-populares-portenas-solicitan-su-apertura-y-funcionamiento-en-forma-parcial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"Las bibliotecas populares porte\u00f1as solicitan su apertura y funcionamiento en forma parcial"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=52281"}],"version-history":[{"count":2,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52281\/revisions"}],"predecessor-version":[{"id":52284,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52281\/revisions\/52284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/52282"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=52281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=52281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=52281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}