{"id":52241,"date":"2020-05-25T01:00:14","date_gmt":"2020-05-25T04:00:14","guid":{"rendered":"http:\/\/vocesdelacomuna15.com.ar\/wordpress\/?p=52241"},"modified":"2020-05-21T23:49:03","modified_gmt":"2020-05-22T02:49:03","slug":"seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/","title":{"rendered":"Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Entre ellos hay dos de la Comuna 15: Argentinos Juniors y Comunicaciones. Ser\u00e1 entre 12.30 y 14 horas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de la cuarentena por el coronavirus, seis clubes\nporte\u00f1os levantar\u00e1n la bandera argentina y la de la solidaridad en el feriado\ndel 25 de mayo. Los hinchas y socios de &nbsp;V\u00e9lez,\nRacing, Argentinos Juniors, All Boys, Ferro y Comunicaciones llevar\u00e1n a cabo un\nlocro en esta fecha patria en sus sedes de la Ciudad de Buenos Aires para\nayudar a aquellos que est\u00e9n sufriendo consecuencias econ\u00f3micas derivadas por la\ngran crisis que dispar\u00f3 el COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;En el marco de la crisis sanitaria y econ\u00f3mica\nmundial, los clubes, como actores fundamentales de la vida social de los\nbarrios, asumimos la responsabilidad de colaborar con nuestros\/as socios\/as y\nvecinos\/as. A pesar de que esta situaci\u00f3n tambi\u00e9n nos golpea, y en muchos casos\ntenemos dificultades para afrontar nuestras obligaciones, no dejaremos de\ncumplir nuestro imprescindible rol comunitario\u201d, expresan los clubes en un\ncomunicado compartido. Y convocan con el lema: \u201cFrente al coronavirus, somos\nuna sola hinchada&#8221;, los clubes se muestran esperanzados en ayudar en estos\nmomentos de crisis y en mostrar su lado m\u00e1s humano, social y solidario\u201d. Por\nredes sociales viralizaron el siguiente mensaje llamando a hinchas, socios o\nvecinos a colaborar: &#8220;Si bien los diferentes clubes de la zona ya venimos\ntrabajando sobre esto hace tiempo, hemos juntado fuerzas para realizar una\nacci\u00f3n m\u00e1s grande e inclusiva. El pr\u00f3ximo lunes 25 de mayo, ven\u00ed a comer al\nclub de tu barrio. Desde las 12.30 hasta las 14 horas, en el punto que te quede\nm\u00e1s cerca&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los clubes que participan y sus direcciones son las\nsiguientes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">All\nBoys : Chivilcoy 1951 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Argentinos\nJuniors: Gavil\u00e1n 2151 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comunicaciones: Av. San Mart\u00edn y Tinogasta <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ferro Carril Oeste : Garc\u00eda Lorca 350 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Racing Club (Sede Villa del Parque) Nogoy\u00e1 3045 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">V\u00e9lez Sarsfield : Av. Juan B. Justo 9200. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caracteres: 1.797<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foto: Twitter<\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_52241\" class=\"pvc_stats all  \" data-element-id=\"52241\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Entre ellos hay dos de la Comuna 15: Argentinos Juniors y Comunicaciones. Ser\u00e1 entre 12.30 y 14 horas En medio de la cuarentena por el coronavirus, seis clubes porte\u00f1os levantar\u00e1n la bandera argentina y la de la solidaridad en el feriado del 25 de mayo. Los hinchas y socios de &nbsp;V\u00e9lez, Racing, Argentinos Juniors, All [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_52241\" class=\"pvc_stats all  \" data-element-id=\"52241\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":52242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6,27,29],"tags":[],"class_list":["post-52241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro","category-deportes","category-lapa","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":260,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T04:00:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/locro-solidario-21052020.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo\",\"datePublished\":\"2020-05-25T04:00:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/\"},\"wordCount\":335,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/locro-solidario-21052020.png\",\"articleSection\":[\"Agronom\u00eda\",\"Deportes\",\"La Paternal\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/\",\"name\":\"Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/locro-solidario-21052020.png\",\"datePublished\":\"2020-05-25T04:00:14+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/locro-solidario-21052020.png\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/locro-solidario-21052020.png\",\"width\":746,\"height\":498},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/","og_locale":"es_ES","og_type":"article","og_title":"Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2020-05-25T04:00:14+00:00","og_image":[{"width":746,"height":498,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/locro-solidario-21052020.png","type":"image\/png"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo","datePublished":"2020-05-25T04:00:14+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/"},"wordCount":335,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/locro-solidario-21052020.png","articleSection":["Agronom\u00eda","Deportes","La Paternal"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/","name":"Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/locro-solidario-21052020.png","datePublished":"2020-05-25T04:00:14+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/locro-solidario-21052020.png","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/locro-solidario-21052020.png","width":746,"height":498},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/seis-clubes-de-la-ciudad-organizan-un-locro-solidario-el-25-de-mayo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"Seis clubes de la Ciudad organizan un locro solidario el 25 de mayo"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=52241"}],"version-history":[{"count":1,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52241\/revisions"}],"predecessor-version":[{"id":52243,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52241\/revisions\/52243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/52242"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=52241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=52241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=52241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}