{"id":52232,"date":"2020-05-19T11:48:18","date_gmt":"2020-05-19T14:48:18","guid":{"rendered":"http:\/\/vocesdelacomuna15.com.ar\/wordpress\/?p=52232"},"modified":"2020-05-19T11:48:24","modified_gmt":"2020-05-19T14:48:24","slug":"mapa-de-casos-de-dengue-en-parque-chas","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/","title":{"rendered":"Mapa de casos de dengue en Parque Chas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> Relevamiento de la Unidad B\u00e1sica Monteagudo <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la Unidad B\u00e1sica Monteagudo hicieron este mapeo de los\ncasos de dengue confirmados en el barrio de Parque Chas, por cuadra y por\nmanzana. Se puede ver este trabajo en el siguiente link: <a href=\"https:\/\/www.google.com\/maps\/d\/edit?mid=1TCqY14cimlsbBJhsXwiC1-x0umQIwiBm&amp;usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.com\/maps\/d\/edit?mid=1TCqY14cimlsbBJhsXwiC1-x0umQIwiBm&amp;usp=sharing<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reproducimos aqu\u00ed parte del comunicado de la UB Monteagudo,\nsituada en Victorica 2743, esquina Dubl\u00edn:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra\nidea es:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u27a1\ufe0fPoder conocer todas las manzanas con casos de dengue,\npara alertarnxs a realizar y tomar medidas de prevenci\u00f3n necesarias (que\nabajo&nbsp;se describen), sobre todo en las manzanas con casos, y en las\naleda\u00f1as.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u27a1\ufe0f Difundirlo a todx vecinx es prioridad, para que las\nmedidas de prevenci\u00f3n puedan tener m\u00e1s efecto. Porque no sirve que un vecinx\nsolx lo realice, sino que lo hagamos todxs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u27a1\ufe0f\u029f\u1d00 \u1d18\u0280\u1d07\u1d20\u1d07\u0274\u1d04\u026a\u00f3\u0274 \u1d0d\u00e1s \u026a\u1d0d\u1d18\u1d0f\u0280\u1d1b\u1d00\u0274\u1d1b\u1d07 s\u1d07 \u0280\u1d07\u1d00\u029f\u026a\u1d22\u1d00 \u1d07\u0274\n\u026a\u0274\u1d20\u026a\u1d07\u0280\u0274\u1d0f.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.\nElimin\u00e1 toda acumulaci\u00f3n de agua que exista en tu casa (cacharros, cubiertas\nsin uso, etc).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.\nRenov\u00e1 como m\u00ednimo dos veces por semana el agua de floreros, platos del perro,\netc, para eliminar posibles larvas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">. Us\u00e1\nrepelente especialmente en las primeras horas de la ma\u00f1ana y en las \u00faltimas del\nd\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">. Tir\u00e1\nperi\u00f3dicamente agua hirviendo en las rejillas o lugares de dif\u00edcil acceso,\ndonde pueda haber agua acumulada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">. Tap\u00e1\nel tanque de agua de tu casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Si pose\u00e9s alguno de los siguientes s\u00edntomas, acercate al\ncentro de atenci\u00f3n de salud m\u00e1s cercano, o para sacarte la duda llam\u00e1 0800 222\n0651 (Naci\u00f3n) o 107 (Ciudad)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25aa\ufe0fFiebre alta<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25aa\ufe0fIntenso malestar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25aa\ufe0fN\u00e1useas y v\u00f3mitos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25aa\ufe0fCansancio intenso<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25aa\ufe0fDolor de cabeza y detr\u00e1s de los ojos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25aa\ufe0fDolores musculares y articulares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25aa\ufe0fAparici\u00f3n de manchas en la piel (con o sin picaz\u00f3n)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25aa\ufe0fPicaz\u00f3n o sangrado de nariz y enc\u00edas (en caso del\nhemorr\u00e1gico)<\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_52232\" class=\"pvc_stats all  \" data-element-id=\"52232\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Relevamiento de la Unidad B\u00e1sica Monteagudo Desde la Unidad B\u00e1sica Monteagudo hicieron este mapeo de los casos de dengue confirmados en el barrio de Parque Chas, por cuadra y por manzana. Se puede ver este trabajo en el siguiente link: https:\/\/www.google.com\/maps\/d\/edit?mid=1TCqY14cimlsbBJhsXwiC1-x0umQIwiBm&amp;usp=sharing Reproducimos aqu\u00ed parte del comunicado de la UB Monteagudo, situada en Victorica 2743, esquina [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_52232\" class=\"pvc_stats all  \" data-element-id=\"52232\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":52233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30,8],"tags":[],"class_list":["post-52232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pchas","category-sociedad","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":300,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mapa de casos de dengue en Parque Chas - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapa de casos de dengue en Parque Chas - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-19T14:48:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-19T14:48:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/dengue1905.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"407\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"Mapa de casos de dengue en Parque Chas\",\"datePublished\":\"2020-05-19T14:48:18+00:00\",\"dateModified\":\"2020-05-19T14:48:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/dengue1905.png\",\"articleSection\":[\"Parque chas\",\"Sociedad\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/\",\"name\":\"Mapa de casos de dengue en Parque Chas - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/dengue1905.png\",\"datePublished\":\"2020-05-19T14:48:18+00:00\",\"dateModified\":\"2020-05-19T14:48:24+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/dengue1905.png\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/dengue1905.png\",\"width\":850,\"height\":407},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/mapa-de-casos-de-dengue-en-parque-chas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa de casos de dengue en Parque Chas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapa de casos de dengue en Parque Chas - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/","og_locale":"es_ES","og_type":"article","og_title":"Mapa de casos de dengue en Parque Chas - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2020-05-19T14:48:18+00:00","article_modified_time":"2020-05-19T14:48:24+00:00","og_image":[{"width":850,"height":407,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/dengue1905.png","type":"image\/png"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"Mapa de casos de dengue en Parque Chas","datePublished":"2020-05-19T14:48:18+00:00","dateModified":"2020-05-19T14:48:24+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/dengue1905.png","articleSection":["Parque chas","Sociedad"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/","name":"Mapa de casos de dengue en Parque Chas - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/dengue1905.png","datePublished":"2020-05-19T14:48:18+00:00","dateModified":"2020-05-19T14:48:24+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/dengue1905.png","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/dengue1905.png","width":850,"height":407},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/mapa-de-casos-de-dengue-en-parque-chas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"Mapa de casos de dengue en Parque Chas"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=52232"}],"version-history":[{"count":1,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52232\/revisions"}],"predecessor-version":[{"id":52234,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52232\/revisions\/52234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/52233"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=52232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=52232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=52232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}