{"id":52224,"date":"2020-05-18T15:34:39","date_gmt":"2020-05-18T18:34:39","guid":{"rendered":"http:\/\/vocesdelacomuna15.com.ar\/wordpress\/?p=52224"},"modified":"2020-05-18T15:34:44","modified_gmt":"2020-05-18T18:34:44","slug":"comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/","title":{"rendered":"Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Enviado por los Vecinos Autoconvocados contra el Megaestadio Movistar Arena<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pr\u00f3ximo\njueves 21 de mayo la Legislatura tratar\u00e1 un proyecto de ley para rezonificar\ndos terrenos que se encuentran linderos a la futura estaci\u00f3n Villa Crespo del\nFFC San Mar\u00edn, sobre la Av. Corrientes 6094\/6102.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos terrenos\nfueron cedidos por la Agencia de Administraci\u00f3n de Bienes del Estado (AABE) a\nla Ciudad de Buenos Aires a pocas semanas de terminar el mandato de Mauricio\nMacri en la presidencia de la Naci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una sesi\u00f3n de\nla Legislatura realizada en noviembre de 2019 se autoriz\u00f3 la venta de esos\nterrenos y solo faltaba la aprobaci\u00f3n para que, rezonificaci\u00f3n mediante, se\nautorizara la construcci\u00f3n de dos torres de 45 metros de altura, a ambos lados\ndel viaducto, avanzando as\u00ed en completar un negocio inmobiliario que girar\u00e1\nalrededor del MEGAESTADIO MOVISTAR ARENA, tal como venimos denunciando los\nVecinos Autoconvocados contra el MEGAESTADIO desde hace dos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estos\nproyectos no s\u00f3lo quieren cambiar violenta y arbitrariamente la fisonom\u00eda y la\nhistoria de nuestro barrio, sino tambi\u00e9n desalojar a la Asamblea de Corrientes\ny Juan B. Justo y la Radio Asamblea, que desde el a\u00f1o 2001 funcionan en uno de\nlos terrenos que pretender rematar. Ya lo hicieron con locales de la zona\nalrededor del MEGAESTADIO para instalar bares, cervecer\u00edas, comercios que giran\nalrededor de ese gran negocio cuyos due\u00f1os son el Diario La Naci\u00f3n, la\nmultinacional AEG y MOVISTAR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En momentos en\nque gran parte del mundo plantea la necesidad de desarrollo sustentables,\nnuestros representantes van por una ciudad con m\u00e1s cemento, menor calidad de\nvida para sus habitantes, polos comerciales de enorme concentraci\u00f3n de gente y\ngrandes negocios para muy pocos, los de siempre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras durante\nesta cuarentena impuesta para controlar la pandemia de CORONAVIRUS quienes nos\nencontramos afectados y perjudicados por estos nefastos negocios no podemos\nmanifestarnos, el ejecutivo y la legislatura contin\u00faan trabajando para aumentar\nlas fortunas de los Grupos La Naci\u00f3n, Telef\u00f3nica y AEG Worldwide. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apelamos a la\nsensatez y buen criterio de legisladoras y legisladores para que el pr\u00f3ximo\njueves no den los votos para avanzar en la destrucci\u00f3n de un barrio como Villa\nCrespo, con su historia y tradici\u00f3n. Nos dirigimos fundamentalmente a los\nbloques de la UCR-Evoluci\u00f3n; Partido Socialista y Coalici\u00f3n C\u00edvica para que\ndejen de ser socios del oficialismo en este proyecto y miren la realidad de lo\nque est\u00e1 pasando en nuestro barrio y escuchen a los vecinos y vecinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, nos\ndirigimos a los medios de comunicaci\u00f3n, para que nos escuchen en estos reclamos\ne interpelen a funcionarios y legisladoras y legisladores acerca de si se van a\ndefinir por seguir aumentando los negocios inmobiliarios de unos pocos en\ncomplicidad con el gobierno de la Ciudad, o lo van a hacer a favor de quienes\nles dieron los votos para que legislen a favor de los ciudadanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NO M\u00c1S VENTAS DE TERRENOS PARA NEGOCIADOS\nINMOBILIARIOS.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NO AL DESALOJO DE LA ASAMBLEA DE CORRIENTES Y JUAN\nB. JUSTO Y DE LA RADIO ASAMBLEA.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NO AL MEGAESTADIO MOVISTAR ARENA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SI A VILLA CRESPO \u2013 NO A VILLA ARENA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vecinos Autoconvocados contra el MEGAESTADIO\nMOVISTAR ARENA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CONTACTOS:\n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gustavo: &nbsp;15 6 180 0310<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ingrid: &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;15 5 494 0643<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laura: &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;15 5 697 2643<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luis: &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;15 5 709 2692<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paula:&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;15\n5\n817-2832<\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_52224\" class=\"pvc_stats all  \" data-element-id=\"52224\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Enviado por los Vecinos Autoconvocados contra el Megaestadio Movistar Arena El pr\u00f3ximo jueves 21 de mayo la Legislatura tratar\u00e1 un proyecto de ley para rezonificar dos terrenos que se encuentran linderos a la futura estaci\u00f3n Villa Crespo del FFC San Mar\u00edn, sobre la Av. Corrientes 6094\/6102. Estos terrenos fueron cedidos por la Agencia de Administraci\u00f3n [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_52224\" class=\"pvc_stats all  \" data-element-id=\"52224\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":52225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8,32],"tags":[],"class_list":["post-52224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","category-vcre","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":231,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-18T18:34:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-18T18:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/estadio-arena-18052020.png\" \/>\n\t<meta property=\"og:image:width\" content=\"507\" \/>\n\t<meta property=\"og:image:height\" content=\"468\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d\",\"datePublished\":\"2020-05-18T18:34:39+00:00\",\"dateModified\":\"2020-05-18T18:34:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/\"},\"wordCount\":592,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/estadio-arena-18052020.png\",\"articleSection\":[\"Sociedad\",\"Villa Crespo\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/\",\"name\":\"Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/estadio-arena-18052020.png\",\"datePublished\":\"2020-05-18T18:34:39+00:00\",\"dateModified\":\"2020-05-18T18:34:44+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/estadio-arena-18052020.png\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/estadio-arena-18052020.png\",\"width\":507,\"height\":468},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/","og_locale":"es_ES","og_type":"article","og_title":"Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2020-05-18T18:34:39+00:00","article_modified_time":"2020-05-18T18:34:44+00:00","og_image":[{"width":507,"height":468,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/estadio-arena-18052020.png","type":"image\/png"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d","datePublished":"2020-05-18T18:34:39+00:00","dateModified":"2020-05-18T18:34:44+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/"},"wordCount":592,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/estadio-arena-18052020.png","articleSection":["Sociedad","Villa Crespo"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/","name":"Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/estadio-arena-18052020.png","datePublished":"2020-05-18T18:34:39+00:00","dateModified":"2020-05-18T18:34:44+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/estadio-arena-18052020.png","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/estadio-arena-18052020.png","width":507,"height":468},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/comunicado-de-prensa-no-a-villa-arena-si-a-villa-crespo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"Comunicado de Prensa: \u201cNo a Villa Arena \u2013 S\u00ed a Villa Crespo\u201d"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=52224"}],"version-history":[{"count":1,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52224\/revisions"}],"predecessor-version":[{"id":52226,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52224\/revisions\/52226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/52225"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=52224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=52224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=52224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}