{"id":52210,"date":"2020-05-18T14:02:15","date_gmt":"2020-05-18T17:02:15","guid":{"rendered":"http:\/\/vocesdelacomuna15.com.ar\/wordpress\/?p=52210"},"modified":"2020-05-20T15:22:41","modified_gmt":"2020-05-20T18:22:41","slug":"szymsia-bajour-un-violinista-entremundos","status":"publish","type":"post","link":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/","title":{"rendered":"Szymsia Bajour, un violinista entremundos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">De Polonia a La Paternal. Nota: Amadeo Espina para www.vocesdelacomuna15.com.ar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Szymsia Bajour fue uno de los\nm\u00fasicos argentinos m\u00e1s destacados del siglo XX. Su vida transcurri\u00f3 a lo largo\nde muy variados y dis\u00edmiles mundos. Los significantes yiddish y lunfardo\nrioplatense, tango y m\u00fasica cl\u00e1sica, Varsovia y Buenos Aires, nos remiten a\nsignificados diferentes, sino antag\u00f3nicos, y son algunos de los que encarnaron\nla vida de este violinista, polaco de nacimiento, pero argentino por adopci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Naci\u00f3 en el a\u00f1o 1928 en el seno\nde una familia jud\u00eda en el pueblo de Nasielsk, una localidad cercana a\nVarsovia, capital de Polonia. Ya en sus primeros a\u00f1os de vida demostr\u00f3 inter\u00e9s\npor la m\u00fasica y particularmente por el viol\u00edn. Comenz\u00f3 a estudiar con un\nviolinista del pueblo, quien al poco tiempo not\u00f3 que Szymsia pose\u00eda un talento\npor encima de la media. \u00c9l convenci\u00f3 a los padres de Szymsia, de que su hijo\ndeb\u00eda tomar clases con un violinista profesional. Al poco tiempo ingres\u00f3 a la\nclase del profesor William Krishtal, en el Conservatorio de Varsovia. Esta\ninstituci\u00f3n era un importante centro de formaci\u00f3n musical en Europa. All\u00ed\ninterpret\u00f3, junto a la orquesta del conservatorio y a los 9 a\u00f1os de edad, uno\nde los conciertos m\u00e1s destacados del repertorio violin\u00edstico, el Concierto de\nF.Mendelssohn. Su vida parec\u00eda encaminada a ser la de un destacado concertista.\nSin embargo, al mismo tiempo fuera de los claustros educativos, la sociedad\neuropea se dirig\u00eda con paso firme a la cat\u00e1strofe. El antisemitismo se tornaba\ncada vez m\u00e1s fuerte y una guerra en todo el continente parec\u00eda inexorable. En\nese contexto Samuel Bajour, padre de Szymsia, decidi\u00f3 en 1938 emigrar con toda\nla familia a Buenos Aires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La familia Bajour se instal\u00f3 en\nuna casa de la calle A\u00f1asco del barrio de La Paternal y Samuel Bajour estableci\u00f3\nen la misma vivienda un comercio de carb\u00f3n. Los primeros a\u00f1os fueron duros. No solo\ndispon\u00eda la familia de menores ingresos que en Polonia, sino que deb\u00edan\nadaptarse a un medio social completamente diferente. A pesar de las\ndificultades, los padres de Szymsia procuraron que su hijo contin\u00fae con los\nestudios del viol\u00edn y consiguieron un profesor particular en el barrio. Como la\nfamilia no ten\u00eda medios econ\u00f3micos suficientes para pagarle con dinero,\nacordaron abonarle las clases con bolsas de carb\u00f3n. As\u00ed transcurrieron cuatro\na\u00f1os dif\u00edciles, hasta que en un d\u00eda de 1942 la vida de Szymsia tuvo cambio\ndecisivo. Samuel Bajour vio un aviso en el diario, en el que se buscaba un\nviolinista para un sexteto que anime los bailes de carnaval del Club Villa Ballester,\ny avizor\u00f3 all\u00ed una oportunidad para que su hijo haga un aporte a la precaria\neconom\u00eda familiar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Szymsia se present\u00f3 para el\npuesto y, luego de interpretar una pieza cl\u00e1sica, fue inmediatamente contratado.\nSu salario consist\u00eda en 11 pesos de aquel entonces, que era m\u00e1s de lo que\ncualquier trabajador como su padre pod\u00eda ganar. Luego de esta experiencia,\ningres\u00f3 Bajour a la orquesta t\u00edpica de Roberto Velo, que se presentaba en el\nic\u00f3nico cabaret Tibidabo. Si bien la orquesta de Velo era de segunda l\u00ednea, en\nese mismo espacio se presentaban algunas de las orquestas t\u00edpicas m\u00e1s importantes\nde aquel entonces, como la de An\u00edbal Troilo y Osvaldo Pugliese. De este modo\nBajour fue gan\u00e1ndose un nombre en el ambiente y escalando a lo largo de\ndiferentes agrupaciones. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1950 ingres\u00f3 a la reconocida\norquesta de Carlos di Sarli. Paralelamente tuvo participaciones en varias de\nlas orquestas m\u00e1s prestigiosas de esos a\u00f1os, como la de Pugliese y la de\nStampone. \u00c1stor Piazzolla, siendo a\u00fan un veintea\u00f1ero integrante de la orquesta\nde Troilo, hab\u00eda conocido a Bajour a principios los \u00b440 en el mencionado\nTibidabo. En 1960 convoc\u00f3 Piazzolla a Bajour para formar su primer quinteto, que\nse complet\u00f3 con Kicho D\u00edaz, Horacio Malvicino y Jaime Gosis. Esta nueva\nagrupaci\u00f3n fue un hito en la historia del tango, a la vez que una ruptura con\nlas tradiciones musicales contempor\u00e1neas. Una de las principales diferencias\nrespecto a las orquestas t\u00edpicas del momento, era que Piazzolla le daba en el\nquinteto un rol mucho m\u00e1s solista y virtuoso a cada instrumento. En 1961\ngrabaron un deslumbrante disco llamado <em>Piazzolla Interpreta a Piazzolla<\/em>,\nel cual contiene el primer registro de Adi\u00f3s Nonino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante los a\u00f1os \u00b4\u00b450 Bajour hab\u00eda formado una familia y ten\u00eda abundante trabajo. No obstante, un esp\u00edritu inquieto lo llev\u00f3 a buscar nuevos horizontes. Paralelamente a una muy exitosa carrera en el mundo del tango, no abandon\u00f3 Bajour la m\u00fasica cl\u00e1sica, a pesar de si haberla dejado en un segundo plano. En los \u00b440 hab\u00eda comenzado a tomar clases de viol\u00edn con el famoso maestro Ljerko Spiller y en 1949 hab\u00eda ganado un concurso para integrar la Orquesta Sinf\u00f3nica Nacional Argentina. En 1961 recibi\u00f3 una invitaci\u00f3n para tomar el puesto de concertino de la Orquesta Nacional de Cuba. Ser concertino de una orquesta sinf\u00f3nica ofrec\u00eda un importante y nuevo desaf\u00edo profesional en el mundo de la m\u00fasica cl\u00e1sica. Adem\u00e1s durante los a\u00f1os en el tango, hab\u00eda desarrollado Bajour una afinidad pol\u00edtica por el socialismo y comunismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta suma de factores lo llevaron a aceptar la invitaci\u00f3n y mudarse en 1961 con toda su familia a La Habana. Sin embargo, al poco tiempo de instalarse, result\u00f3 este nuevo hogar ser solo una nueva y breve escala. Las relaciones que la URSS entabl\u00f3 con Cuba, hicieron que el violinista sovi\u00e9tico David Oistrach, uno de los violinistas m\u00e1s famosos del siglo XX y muy admirado por Bajour, viaje a Cuba para dar una serie de conciertos. En ese marco entabl\u00f3 Bajour un contacto con Oistrach, y este le ofreci\u00f3 en 1963 una beca para que realice un estudio perfeccionamiento de dos a\u00f1os en su c\u00e1tedra en el Conservatorio Tschaikovski de Mosc\u00fa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta instituci\u00f3n era entonces la\nm\u00e1xima referencia en el \u00e1mbito de la formaci\u00f3n musical cl\u00e1sica de Rusia y el\nmundo de rep\u00fablicas socialistas. Era para Bajour una oportunidad insoslayable.\nSu familia regres\u00f3 a Buenos Aires y \u00e9l se traslad\u00f3 solo a Mosc\u00fa. De alg\u00fan modo\nesto signific\u00f3 retomar parte del mundo que hab\u00eda dejado atr\u00e1s en Polonia y\ncompletar la formaci\u00f3n de concertista cl\u00e1sico al m\u00e1ximo nivel. Luego de cumplir\nexitosamente con sus estudios en Mosc\u00fa volvi\u00f3 en 1965 a Cuba, donde se\nreencontr\u00f3 con su familia. Al poco tiempo advirti\u00f3 que en Cuba no ten\u00eda muchos\nnuevos desaf\u00edos art\u00edsticos por delante, ya que era el concertino de la orquesta,\nel puesto m\u00e1ximo al que all\u00ed pod\u00eda aspirar. Esto, sumado a que su esposa era\nargentina y sus hijos estaban lejos del resto de la familia, llev\u00f3 a que\ndecidieran retornar a Buenos Aires en 1967.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de algunos a\u00f1os en el exterior Bajour necesitaba reinsertarse en la escena musical argentina. En 1969 fue invitado para interpretar el Concierto de J. Brahms, acompa\u00f1ado por Ensamble Musical de Buenos Aires. Este concierto le otorg\u00f3 en el ambiente un reconocimiento que le abri\u00f3 las puertas a una carrera como solista cl\u00e1sico. Se sucedieron a lo largo de los siguientes a\u00f1os importantes presentaciones en Argentina y el exterior. Se destacan algunas como un concierto solista acompa\u00f1ado por la Orquesta Filarm\u00f3nica de Buenos Aires en el Teatro Col\u00f3n, el estreno latinoamericano del concierto para viol\u00edn del compositor polaco Krzysztof Penderecki y varias giras nacionales e internacionales.\nEsto signific\u00f3, a\u00f1os despu\u00e9s, concretar la carrera de concertista solista para\nla que hab\u00eda comenzado a prepararse de ni\u00f1o en Polonia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paralelamente a la carrera que\nBajour estaba desarrollando, se fue despertando y haciendo cada vez m\u00e1s fuerte\nen \u00e9l una vocaci\u00f3n por la pedagog\u00eda. Luego de volver de Cuba, comenz\u00f3 a dar\nclases particulares y al poco tiempo era uno de los principales maestros de\nviol\u00edn de Buenos Aires. Muchos de sus disc\u00edpulos, como Daniel Zisman, Pablo\nSarav\u00ed y Alejandro Rutkauskas, se transformaron luego en destacados violinistas,\nmaestros y solistas, que realizaron una carrera tanto en la Argentina como en\nel exterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mediados de los \u00b470 se\nencontraba Bajour arraigado en Argentina y desarrollando una intensa actividad\nart\u00edstica. No obstante el deterioro social al que condujo la \u00faltima dictadura,\nsuscit\u00f3 consecuencias directas para su vida. A principios de 1976 deb\u00eda dar un\nconcierto como solista junto a la Orquesta Sinf\u00f3nica de Bah\u00eda Blanca. El\nconcierto fue cancelado porque su nombre pas\u00f3 a formar parte de las llamadas listas\nnegras. El hecho de que hab\u00eda estado en Cuba y la URSS, sumado a que era\nmiembro de la Sociedad Argentina de Relaciones Culturales con la URSS, fueron motivos\nsuficientes para ello. En esa situaci\u00f3n y a partir de una oportuna invitaci\u00f3n\npara integrar la Orquesta Filarm\u00f3nica de las Am\u00e9ricas, decidi\u00f3 exiliarse en 1976\nen M\u00e9xico, donde la orquesta desarrollaba su actividad. A los pocos meses fue\ncontratado como concertino por la Orquesta Sinf\u00f3nica de Xalapa. Luego de cuatro\na\u00f1os no exentos de dificultades, con un breve \u00ednterin en que su esposa e hijos\nestuvieron en M\u00e9xico, decidi\u00f3 en 1980 regresar a Argentina. Si bien la\ndictadura segu\u00eda en el poder, Bajour decidi\u00f3 asumir el riesgo de retornar para\nestar junto a su familia. Esta tercera vez, si ser\u00eda la definitiva. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando regres\u00f3, Bajour retom\u00f3 su\nactividad y al poco tiempo obtuvo importantes nombramientos en instituciones\nculturales. En 1982 fue nombrado profesor del Conservatorio Nacional de M\u00fasica\ny en 1984 obtuvo por concurso el cargo de concertino de la Orquesta Estable del\nTeatro Col\u00f3n. Continu\u00f3 con su actividad docente hasta sus \u00faltimos a\u00f1os de vida.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el a\u00f1o 2006 Szymsia Bajour\nfalleci\u00f3 en la Ciudad de Buenos Aires. M\u00e1s all\u00e1 de los conciertos y grabaciones\nque Bajour realiz\u00f3 en el pa\u00eds, cabe destacar dos aspectos que representaron\naportes trascendentales a la cultura argentina. En primer lugar, fue uno de los\nm\u00fasicos que, con una formaci\u00f3n t\u00e9cnica de alto nivel, permitieron el desarrollo\nfundamental que tuvo el tango a mediados del siglo XX. Sin ellos, figuras como\n\u00c1stor Piazzolla nunca hubieran podido concretar sus ideas y transformarse en lo\nque hoy representan. El otro aporte que Bajour dio al pa\u00eds, fue su labor\ndocente. Fue una figura que import\u00f3 directamente un conocimiento que solo unos\npocos maestros pose\u00edan en Argentina y que transmiti\u00f3 y germin\u00f3 en sus numerosos\nalumnos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Form\u00f3 a toda una generaci\u00f3n de\nviolinistas en el pa\u00eds, que est\u00e1 vigente al d\u00eda de hoy y a su vez est\u00e1 encargada\nde formar a siguientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caracteres: 10.256<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foto Principal: Tangos al Bardo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_52210\" class=\"pvc_stats all  \" data-element-id=\"52210\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>De Polonia a La Paternal. Nota: Amadeo Espina para www.vocesdelacomuna15.com.ar Szymsia Bajour fue uno de los m\u00fasicos argentinos m\u00e1s destacados del siglo XX. Su vida transcurri\u00f3 a lo largo de muy variados y dis\u00edmiles mundos. Los significantes yiddish y lunfardo rioplatense, tango y m\u00fasica cl\u00e1sica, Varsovia y Buenos Aires, nos remiten a significados diferentes, sino [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_52210\" class=\"pvc_stats all  \" data-element-id=\"52210\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":52211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[24,29],"tags":[],"class_list":["post-52210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-lapa","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":true,"total_views":663,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Szymsia Bajour, un violinista entremundos - Voces de la Comuna 15<\/title>\n<meta name=\"description\" content=\"Voces de la Comuna 15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Szymsia Bajour, un violinista entremundos - Voces de la Comuna 15\" \/>\n<meta property=\"og:description\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/\" \/>\n<meta property=\"og:site_name\" content=\"Voces de la Comuna 15\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VocesComuna15\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-18T17:02:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-20T18:22:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/Szymnsia-Bajour-.jpg-foto-tangos-al-bardo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federico Arguto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:site\" content=\"@vocescomuna15\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Arguto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/\"},\"author\":{\"name\":\"Federico Arguto\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\"},\"headline\":\"Szymsia Bajour, un violinista entremundos\",\"datePublished\":\"2020-05-18T17:02:15+00:00\",\"dateModified\":\"2020-05-20T18:22:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/\"},\"wordCount\":1853,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Szymnsia-Bajour-.jpg-foto-tangos-al-bardo.jpg\",\"articleSection\":[\"Cultura\",\"La Paternal\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/\",\"name\":\"Szymsia Bajour, un violinista entremundos - Voces de la Comuna 15\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Szymnsia-Bajour-.jpg-foto-tangos-al-bardo.jpg\",\"datePublished\":\"2020-05-18T17:02:15+00:00\",\"dateModified\":\"2020-05-20T18:22:41+00:00\",\"description\":\"Voces de la Comuna 15\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Szymnsia-Bajour-.jpg-foto-tangos-al-bardo.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Szymnsia-Bajour-.jpg-foto-tangos-al-bardo.jpg\",\"width\":225,\"height\":224},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/szymsia-bajour-un-violinista-entremundos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Szymsia Bajour, un violinista entremundos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"name\":\"Voces de la Comuna 15\",\"description\":\"Sitio web de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#organization\",\"name\":\"Voces de la Comuna 15\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_voces.jpg\",\"width\":512,\"height\":512,\"caption\":\"Voces de la Comuna 15\"},\"image\":{\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VocesComuna15\\\/\",\"https:\\\/\\\/x.com\\\/vocescomuna15\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/#\\\/schema\\\/person\\\/4739e109db25d799cd3d139eeb509e43\",\"name\":\"Federico Arguto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"contentUrl\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367\",\"caption\":\"Federico Arguto\"},\"url\":\"https:\\\/\\\/vocesdelacomuna15.com.ar\\\/press\\\/author\\\/fede\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Szymsia Bajour, un violinista entremundos - Voces de la Comuna 15","description":"Voces de la Comuna 15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/","og_locale":"es_ES","og_type":"article","og_title":"Szymsia Bajour, un violinista entremundos - Voces de la Comuna 15","og_description":"Voces de la Comuna 15","og_url":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/","og_site_name":"Voces de la Comuna 15","article_publisher":"https:\/\/www.facebook.com\/VocesComuna15\/","article_published_time":"2020-05-18T17:02:15+00:00","article_modified_time":"2020-05-20T18:22:41+00:00","og_image":[{"width":225,"height":224,"url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/Szymnsia-Bajour-.jpg-foto-tangos-al-bardo.jpg","type":"image\/jpeg"}],"author":"Federico Arguto","twitter_card":"summary_large_image","twitter_creator":"@vocescomuna15","twitter_site":"@vocescomuna15","twitter_misc":{"Escrito por":"Federico Arguto","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/#article","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/"},"author":{"name":"Federico Arguto","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43"},"headline":"Szymsia Bajour, un violinista entremundos","datePublished":"2020-05-18T17:02:15+00:00","dateModified":"2020-05-20T18:22:41+00:00","mainEntityOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/"},"wordCount":1853,"commentCount":0,"publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/Szymnsia-Bajour-.jpg-foto-tangos-al-bardo.jpg","articleSection":["Cultura","La Paternal"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/","name":"Szymsia Bajour, un violinista entremundos - Voces de la Comuna 15","isPartOf":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/#primaryimage"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/#primaryimage"},"thumbnailUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/Szymnsia-Bajour-.jpg-foto-tangos-al-bardo.jpg","datePublished":"2020-05-18T17:02:15+00:00","dateModified":"2020-05-20T18:22:41+00:00","description":"Voces de la Comuna 15","breadcrumb":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/#primaryimage","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/Szymnsia-Bajour-.jpg-foto-tangos-al-bardo.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2020\/05\/Szymnsia-Bajour-.jpg-foto-tangos-al-bardo.jpg","width":225,"height":224},{"@type":"BreadcrumbList","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/szymsia-bajour-un-violinista-entremundos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/vocesdelacomuna15.com.ar\/press\/"},{"@type":"ListItem","position":2,"name":"Szymsia Bajour, un violinista entremundos"}]},{"@type":"WebSite","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#website","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","name":"Voces de la Comuna 15","description":"Sitio web de noticias","publisher":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vocesdelacomuna15.com.ar\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#organization","name":"Voces de la Comuna 15","url":"https:\/\/vocesdelacomuna15.com.ar\/press\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/uploads\/2024\/12\/cropped-logo_voces.jpg","width":512,"height":512,"caption":"Voces de la Comuna 15"},"image":{"@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VocesComuna15\/","https:\/\/x.com\/vocescomuna15"]},{"@type":"Person","@id":"https:\/\/vocesdelacomuna15.com.ar\/press\/#\/schema\/person\/4739e109db25d799cd3d139eeb509e43","name":"Federico Arguto","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","url":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","contentUrl":"https:\/\/vocesdelacomuna15.com.ar\/wp-content\/litespeed\/avatar\/82faf979976f1bae889b8b71f8a0a7e5.jpg?ver=1784073367","caption":"Federico Arguto"},"url":"https:\/\/vocesdelacomuna15.com.ar\/press\/author\/fede\/"}]}},"_links":{"self":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/comments?post=52210"}],"version-history":[{"count":4,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52210\/revisions"}],"predecessor-version":[{"id":52237,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/posts\/52210\/revisions\/52237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media\/52211"}],"wp:attachment":[{"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/media?parent=52210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/categories?post=52210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdelacomuna15.com.ar\/press\/wp-json\/wp\/v2\/tags?post=52210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}